{"id":1192,"date":"2018-12-19T11:22:13","date_gmt":"2018-12-19T17:22:13","guid":{"rendered":"http:\/\/abrahamcadena.com.mx\/?p=1192"},"modified":"2022-01-02T10:45:27","modified_gmt":"2022-01-02T16:45:27","slug":"camino-a-alcocer","status":"publish","type":"post","link":"https:\/\/sites1.cheverin.com\/abrahamcadena\/2018\/12\/19\/camino-a-alcocer\/","title":{"rendered":"Camino a alcocer"},"content":{"rendered":"<h3><strong>Terreno ubicado en camino hacia a alcocer, muy cerca del hospital\u00a0 MAC.<\/strong><\/h3>\n<p>&nbsp;<\/p>\n<h1>$ 800,000 MXN<\/h1>\n<p>&nbsp;<\/p>\n<h3><strong>Sup: 378\u00a0 M2\u00a0 \u00a0<\/strong><\/h3>\n<h3>Frente:\u00a0 21<\/h3>\n<h3>Fondo:\u00a0 18<\/h3>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>Google maps:<\/p>\n<p><a href=\"https:\/\/www.google.com\/maps\/@20.8916966,-100.7201624,3a,60y,147.11h,84.97t\/data=!3m6!1e1!3m4!1shZSWiL4ftEa47w1lhL00hg!2e0!7i13312!8i6656\">https:\/\/www.google.com\/maps\/@20.8916966,-100.7201624,3a,60y,147.11h,84.97t\/data=!3m6!1e1!3m4!1shZSWiL4ftEa47w1lhL00hg!2e0!7i13312!8i6656<\/a><\/p>\n<p>&nbsp;<\/p>\n<div id=\"kad-wp-gallery27\" class=\"kad-wp-gallery kad-light-wp-gallery clearfix kt-gallery-column-3 rowtight\"><div class=\"tcol-lg-4 tcol-md-4 tcol-sm-4 tcol-xs-6 tcol-ss-12 g_item\"><div class=\"grid_item kad_gallery_fade_in gallery_item\"><a href=\"https:\/\/sites1.cheverin.com\/abrahamcadena\/wp-content\/uploads\/sites\/14\/2018\/12\/Captura-de-pantalla-terreno-cesar.png\" data-rel=\"lightbox\" class=\"lightboxhover\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/sites1.cheverin.com\/abrahamcadena\/wp-content\/uploads\/sites\/14\/2018\/12\/Captura-de-pantalla-terreno-cesar-400x400.png\" width=\"400\" height=\"400\" alt=\"\" srcset=\"https:\/\/sites1.cheverin.com\/abrahamcadena\/wp-content\/uploads\/sites\/14\/2018\/12\/Captura-de-pantalla-terreno-cesar-400x400.png 400w, https:\/\/sites1.cheverin.com\/abrahamcadena\/wp-content\/uploads\/sites\/14\/2018\/12\/Captura-de-pantalla-terreno-cesar-150x150.png 150w, https:\/\/sites1.cheverin.com\/abrahamcadena\/wp-content\/uploads\/sites\/14\/2018\/12\/Captura-de-pantalla-terreno-cesar-800x800.png 800w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" class=\"light-dropshaddow\"\/><\/a><\/div><\/div><div class=\"tcol-lg-4 tcol-md-4 tcol-sm-4 tcol-xs-6 tcol-ss-12 g_item\"><div class=\"grid_item kad_gallery_fade_in gallery_item\"><a href=\"https:\/\/sites1.cheverin.com\/abrahamcadena\/wp-content\/uploads\/sites\/14\/2018\/12\/Captura-de-pantalla-2018-12-13-a-las-16.25.48.png\" data-rel=\"lightbox\" class=\"lightboxhover\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/sites1.cheverin.com\/abrahamcadena\/wp-content\/uploads\/sites\/14\/2018\/12\/Captura-de-pantalla-2018-12-13-a-las-16.25.48-400x400.png\" width=\"400\" height=\"400\" alt=\"\" srcset=\"https:\/\/sites1.cheverin.com\/abrahamcadena\/wp-content\/uploads\/sites\/14\/2018\/12\/Captura-de-pantalla-2018-12-13-a-las-16.25.48-400x400.png 400w, https:\/\/sites1.cheverin.com\/abrahamcadena\/wp-content\/uploads\/sites\/14\/2018\/12\/Captura-de-pantalla-2018-12-13-a-las-16.25.48-150x150.png 150w, https:\/\/sites1.cheverin.com\/abrahamcadena\/wp-content\/uploads\/sites\/14\/2018\/12\/Captura-de-pantalla-2018-12-13-a-las-16.25.48-800x800.png 800w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" class=\"light-dropshaddow\"\/><\/a><\/div><\/div><div class=\"tcol-lg-4 tcol-md-4 tcol-sm-4 tcol-xs-6 tcol-ss-12 g_item\"><div class=\"grid_item kad_gallery_fade_in gallery_item\"><a href=\"https:\/\/sites1.cheverin.com\/abrahamcadena\/wp-content\/uploads\/sites\/14\/2018\/12\/20181004_160724.jpg\" data-rel=\"lightbox\" class=\"lightboxhover\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/sites1.cheverin.com\/abrahamcadena\/wp-content\/uploads\/sites\/14\/2018\/12\/20181004_160724-400x400.jpg\" width=\"400\" height=\"400\" alt=\"\" srcset=\"https:\/\/sites1.cheverin.com\/abrahamcadena\/wp-content\/uploads\/sites\/14\/2018\/12\/20181004_160724-400x400.jpg 400w, https:\/\/sites1.cheverin.com\/abrahamcadena\/wp-content\/uploads\/sites\/14\/2018\/12\/20181004_160724-150x150.jpg 150w, https:\/\/sites1.cheverin.com\/abrahamcadena\/wp-content\/uploads\/sites\/14\/2018\/12\/20181004_160724-800x800.jpg 800w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" class=\"light-dropshaddow\"\/><\/a><\/div><\/div><div class=\"tcol-lg-4 tcol-md-4 tcol-sm-4 tcol-xs-6 tcol-ss-12 g_item\"><div class=\"grid_item kad_gallery_fade_in gallery_item\"><a href=\"https:\/\/sites1.cheverin.com\/abrahamcadena\/wp-content\/uploads\/sites\/14\/2018\/12\/20181004_160713.jpg\" data-rel=\"lightbox\" class=\"lightboxhover\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/sites1.cheverin.com\/abrahamcadena\/wp-content\/uploads\/sites\/14\/2018\/12\/20181004_160713-400x400.jpg\" width=\"400\" height=\"400\" alt=\"\" srcset=\"https:\/\/sites1.cheverin.com\/abrahamcadena\/wp-content\/uploads\/sites\/14\/2018\/12\/20181004_160713-400x400.jpg 400w, https:\/\/sites1.cheverin.com\/abrahamcadena\/wp-content\/uploads\/sites\/14\/2018\/12\/20181004_160713-150x150.jpg 150w, https:\/\/sites1.cheverin.com\/abrahamcadena\/wp-content\/uploads\/sites\/14\/2018\/12\/20181004_160713-730x730.jpg 730w, https:\/\/sites1.cheverin.com\/abrahamcadena\/wp-content\/uploads\/sites\/14\/2018\/12\/20181004_160713-365x365.jpg 365w, https:\/\/sites1.cheverin.com\/abrahamcadena\/wp-content\/uploads\/sites\/14\/2018\/12\/20181004_160713-540x540.jpg 540w, https:\/\/sites1.cheverin.com\/abrahamcadena\/wp-content\/uploads\/sites\/14\/2018\/12\/20181004_160713-270x270.jpg 270w, https:\/\/sites1.cheverin.com\/abrahamcadena\/wp-content\/uploads\/sites\/14\/2018\/12\/20181004_160713-800x800.jpg 800w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" class=\"light-dropshaddow\"\/><\/a><\/div><\/div><div class=\"tcol-lg-4 tcol-md-4 tcol-sm-4 tcol-xs-6 tcol-ss-12 g_item\"><div class=\"grid_item kad_gallery_fade_in gallery_item\"><a href=\"https:\/\/sites1.cheverin.com\/abrahamcadena\/wp-content\/uploads\/sites\/14\/2018\/12\/20181004_160619.jpg\" data-rel=\"lightbox\" class=\"lightboxhover\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/sites1.cheverin.com\/abrahamcadena\/wp-content\/uploads\/sites\/14\/2018\/12\/20181004_160619-400x400.jpg\" width=\"400\" height=\"400\" alt=\"\" srcset=\"https:\/\/sites1.cheverin.com\/abrahamcadena\/wp-content\/uploads\/sites\/14\/2018\/12\/20181004_160619-400x400.jpg 400w, https:\/\/sites1.cheverin.com\/abrahamcadena\/wp-content\/uploads\/sites\/14\/2018\/12\/20181004_160619-150x150.jpg 150w, https:\/\/sites1.cheverin.com\/abrahamcadena\/wp-content\/uploads\/sites\/14\/2018\/12\/20181004_160619-800x800.jpg 800w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" class=\"light-dropshaddow\"\/><\/a><\/div><\/div><div class=\"tcol-lg-4 tcol-md-4 tcol-sm-4 tcol-xs-6 tcol-ss-12 g_item\"><div class=\"grid_item kad_gallery_fade_in gallery_item\"><a href=\"https:\/\/sites1.cheverin.com\/abrahamcadena\/wp-content\/uploads\/sites\/14\/2018\/12\/20181004_160548.jpg\" data-rel=\"lightbox\" class=\"lightboxhover\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/sites1.cheverin.com\/abrahamcadena\/wp-content\/uploads\/sites\/14\/2018\/12\/20181004_160548-400x400.jpg\" width=\"400\" height=\"400\" alt=\"\" srcset=\"https:\/\/sites1.cheverin.com\/abrahamcadena\/wp-content\/uploads\/sites\/14\/2018\/12\/20181004_160548-400x400.jpg 400w, https:\/\/sites1.cheverin.com\/abrahamcadena\/wp-content\/uploads\/sites\/14\/2018\/12\/20181004_160548-150x150.jpg 150w, https:\/\/sites1.cheverin.com\/abrahamcadena\/wp-content\/uploads\/sites\/14\/2018\/12\/20181004_160548-800x800.jpg 800w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" class=\"light-dropshaddow\"\/><\/a><\/div><\/div><div class=\"tcol-lg-4 tcol-md-4 tcol-sm-4 tcol-xs-6 tcol-ss-12 g_item\"><div class=\"grid_item kad_gallery_fade_in gallery_item\"><a href=\"https:\/\/sites1.cheverin.com\/abrahamcadena\/wp-content\/uploads\/sites\/14\/2018\/12\/20181004_160424.jpg\" data-rel=\"lightbox\" class=\"lightboxhover\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/sites1.cheverin.com\/abrahamcadena\/wp-content\/uploads\/sites\/14\/2018\/12\/20181004_160424-400x400.jpg\" width=\"400\" height=\"400\" alt=\"\" srcset=\"https:\/\/sites1.cheverin.com\/abrahamcadena\/wp-content\/uploads\/sites\/14\/2018\/12\/20181004_160424-400x400.jpg 400w, https:\/\/sites1.cheverin.com\/abrahamcadena\/wp-content\/uploads\/sites\/14\/2018\/12\/20181004_160424-150x150.jpg 150w, https:\/\/sites1.cheverin.com\/abrahamcadena\/wp-content\/uploads\/sites\/14\/2018\/12\/20181004_160424-800x800.jpg 800w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" class=\"light-dropshaddow\"\/><\/a><\/div><\/div><div class=\"tcol-lg-4 tcol-md-4 tcol-sm-4 tcol-xs-6 tcol-ss-12 g_item\"><div class=\"grid_item kad_gallery_fade_in gallery_item\"><a href=\"https:\/\/sites1.cheverin.com\/abrahamcadena\/wp-content\/uploads\/sites\/14\/2018\/12\/20181004_160421.jpg\" data-rel=\"lightbox\" class=\"lightboxhover\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/sites1.cheverin.com\/abrahamcadena\/wp-content\/uploads\/sites\/14\/2018\/12\/20181004_160421-400x400.jpg\" width=\"400\" height=\"400\" alt=\"\" srcset=\"https:\/\/sites1.cheverin.com\/abrahamcadena\/wp-content\/uploads\/sites\/14\/2018\/12\/20181004_160421-400x400.jpg 400w, https:\/\/sites1.cheverin.com\/abrahamcadena\/wp-content\/uploads\/sites\/14\/2018\/12\/20181004_160421-150x150.jpg 150w, https:\/\/sites1.cheverin.com\/abrahamcadena\/wp-content\/uploads\/sites\/14\/2018\/12\/20181004_160421-800x800.jpg 800w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" class=\"light-dropshaddow\"\/><\/a><\/div><\/div><div class=\"tcol-lg-4 tcol-md-4 tcol-sm-4 tcol-xs-6 tcol-ss-12 g_item\"><div class=\"grid_item kad_gallery_fade_in gallery_item\"><a href=\"https:\/\/sites1.cheverin.com\/abrahamcadena\/wp-content\/uploads\/sites\/14\/2018\/12\/20181004_160259.jpg\" data-rel=\"lightbox\" class=\"lightboxhover\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/sites1.cheverin.com\/abrahamcadena\/wp-content\/uploads\/sites\/14\/2018\/12\/20181004_160259-400x400.jpg\" width=\"400\" height=\"400\" alt=\"\" srcset=\"https:\/\/sites1.cheverin.com\/abrahamcadena\/wp-content\/uploads\/sites\/14\/2018\/12\/20181004_160259-400x400.jpg 400w, https:\/\/sites1.cheverin.com\/abrahamcadena\/wp-content\/uploads\/sites\/14\/2018\/12\/20181004_160259-150x150.jpg 150w, https:\/\/sites1.cheverin.com\/abrahamcadena\/wp-content\/uploads\/sites\/14\/2018\/12\/20181004_160259-800x800.jpg 800w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" class=\"light-dropshaddow\"\/><\/a><\/div><\/div><div class=\"tcol-lg-4 tcol-md-4 tcol-sm-4 tcol-xs-6 tcol-ss-12 g_item\"><div class=\"grid_item kad_gallery_fade_in gallery_item\"><a href=\"https:\/\/sites1.cheverin.com\/abrahamcadena\/wp-content\/uploads\/sites\/14\/2018\/12\/20181004_160249.jpg\" data-rel=\"lightbox\" class=\"lightboxhover\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/sites1.cheverin.com\/abrahamcadena\/wp-content\/uploads\/sites\/14\/2018\/12\/20181004_160249-400x400.jpg\" width=\"400\" height=\"400\" alt=\"\" srcset=\"https:\/\/sites1.cheverin.com\/abrahamcadena\/wp-content\/uploads\/sites\/14\/2018\/12\/20181004_160249-400x400.jpg 400w, https:\/\/sites1.cheverin.com\/abrahamcadena\/wp-content\/uploads\/sites\/14\/2018\/12\/20181004_160249-150x150.jpg 150w, https:\/\/sites1.cheverin.com\/abrahamcadena\/wp-content\/uploads\/sites\/14\/2018\/12\/20181004_160249-800x800.jpg 800w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" class=\"light-dropshaddow\"\/><\/a><\/div><\/div><div class=\"tcol-lg-4 tcol-md-4 tcol-sm-4 tcol-xs-6 tcol-ss-12 g_item\"><div class=\"grid_item kad_gallery_fade_in gallery_item\"><a href=\"https:\/\/sites1.cheverin.com\/abrahamcadena\/wp-content\/uploads\/sites\/14\/2018\/12\/20181004_160246.jpg\" data-rel=\"lightbox\" class=\"lightboxhover\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/sites1.cheverin.com\/abrahamcadena\/wp-content\/uploads\/sites\/14\/2018\/12\/20181004_160246-400x400.jpg\" width=\"400\" height=\"400\" alt=\"\" srcset=\"https:\/\/sites1.cheverin.com\/abrahamcadena\/wp-content\/uploads\/sites\/14\/2018\/12\/20181004_160246-400x400.jpg 400w, https:\/\/sites1.cheverin.com\/abrahamcadena\/wp-content\/uploads\/sites\/14\/2018\/12\/20181004_160246-150x150.jpg 150w, https:\/\/sites1.cheverin.com\/abrahamcadena\/wp-content\/uploads\/sites\/14\/2018\/12\/20181004_160246-800x800.jpg 800w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" class=\"light-dropshaddow\"\/><\/a><\/div><\/div><\/div>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>Terreno ubicado en camino hacia a alcocer, muy cerca del hospital\u00a0 MAC. &nbsp; $ 800,000 MXN &nbsp; Sup: 378\u00a0 M2\u00a0 \u00a0 Frente:\u00a0 21 Fondo:\u00a0 18 &nbsp; &nbsp; Google maps: https:\/\/www.google.com\/maps\/@20.8916966,-100.7201624,3a,60y,147.11h,84.97t\/data=!3m6!1e1!3m4!1shZSWiL4ftEa47w1lhL00hg!2e0!7i13312!8i6656 &nbsp;<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":33,"featured_media":1200,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-1192","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-real-estate"],"_links":{"self":[{"href":"https:\/\/sites1.cheverin.com\/abrahamcadena\/wp-json\/wp\/v2\/posts\/1192","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sites1.cheverin.com\/abrahamcadena\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sites1.cheverin.com\/abrahamcadena\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sites1.cheverin.com\/abrahamcadena\/wp-json\/wp\/v2\/users\/33"}],"replies":[{"embeddable":true,"href":"https:\/\/sites1.cheverin.com\/abrahamcadena\/wp-json\/wp\/v2\/comments?post=1192"}],"version-history":[{"count":0,"href":"https:\/\/sites1.cheverin.com\/abrahamcadena\/wp-json\/wp\/v2\/posts\/1192\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sites1.cheverin.com\/abrahamcadena\/wp-json\/wp\/v2\/media\/1200"}],"wp:attachment":[{"href":"https:\/\/sites1.cheverin.com\/abrahamcadena\/wp-json\/wp\/v2\/media?parent=1192"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sites1.cheverin.com\/abrahamcadena\/wp-json\/wp\/v2\/categories?post=1192"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sites1.cheverin.com\/abrahamcadena\/wp-json\/wp\/v2\/tags?post=1192"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}